{"id":4404,"date":"2023-02-28T18:28:38","date_gmt":"2023-03-09T19:37:11","guid":{"rendered":"https:\/\/tourtosicily.com\/producto\/el-etna-y-el-vino\/"},"modified":"2023-03-21T10:39:01","modified_gmt":"2023-03-21T09:39:01","slug":"el-etna-y-el-vino","status":"publish","type":"product","link":"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/","title":{"rendered":"El Etna y el vino"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.19.5&#8243; background_color=\u00bbRGBA(255,255,255,0)\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb|12px||12px|false|true\u00bb custom_margin_tablet=\u00bb|5px||5px|false|true\u00bb custom_margin_phone=\u00bb|5px||5px|false|true\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb custom_padding=\u00bb0px|13px|8px|13px|false|true\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_wc_breadcrumb _builder_version=\u00bb4.19.4&#8243; body_line_height=\u00bb1em\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_breadcrumb][et_pb_wc_images show_sale_badge=\u00bboff\u00bb sale_badge_color=\u00bb#076d95&#8243; force_fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.19.5&#8243; sale_badge_custom_padding=\u00bb8px|18px|8px|18px|true|false\u00bb custom_margin=\u00bb-18px||-2px||false|false\u00bb custom_margin_tablet=\u00bb-18px||-2px||false|false\u00bb custom_margin_phone=\u00bb-18px||-2px||false|false\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_rating show_reviews_link=\u00bboff\u00bb _builder_version=\u00bb4.19.5&#8243; rating_text_color=\u00bb#E09900&#8243; custom_margin=\u00bb0em|0em|0em|0em|false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_rating][et_pb_wc_description _builder_version=\u00bb4.20.0&#8243; body_font_size=\u00bb15px\u00bb custom_margin=\u00bb21px||11px|||\u00bb custom_padding=\u00bb4px|||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_description][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb text_line_height=\u00bb1.4em\u00bb header_font=\u00bbPoppins|500|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb18px\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||-8px||false|false\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h4 class=\"western\" lang=\"en-US\">Reservas\u00a0 desde 105 \u20ac por persona \/\/ Descuentos para grupos<\/h4>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/tourtosicily.com\/es\/hacer-una-reserva\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbReservar\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb19px\u00bb button_icon=\u00bb&#xe052;||divi||400&#8243; button_icon_color=\u00bb#FFFFFF\u00bb button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb animation_style=\u00bbslide\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb3px||5px||false|false\u00bb custom_margin_tablet=\u00bb3px||5px||false|false\u00bb custom_margin_phone=\u00bb3px||5px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb27px|15px|7px|22px|false|false\u00bb animation_style=\u00bbslide\u00bb border_radii=\u00bbon|7px|7px|7px|7px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbHind||||||||\u00bb custom_margin=\u00bb||11px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Descripci\u00f3n<\/h3>\n<p>[\/et_pb_text][et_pb_toggle title=\u00bbEl Etna y el vino\u00bb icon_color=\u00bb#0C71C3&#8243; open_icon_color=\u00bb#E09900&#8243; open_use_icon_font_size=\u00bbon\u00bb open_icon_font_size=\u00bb21px\u00bb open_toggle_text_color_tablet=\u00bb\u00bb open_toggle_text_color_phone=\u00bb\u00bb open_toggle_text_color_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb title_font_size=\u00bb14px\u00bb body_text_align=\u00bbjustify\u00bb hover_enabled=\u00bb0&#8243; border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Saliendo de Catania, nuestro personal le recibir\u00e1 en coches reservados en su hotel para una memorable excursi\u00f3n al volc\u00e1n activo m\u00e1s alto de Europa.<\/p>\n<p>Tras admirar los bosques, cr\u00e1teres y coladas de lava antiguas y recientes, nos detendremos en una importante bodega para visitar las cavas y degustar una selecci\u00f3n de vinos seleccionados por sumilleres, acompa\u00f1ados de catas de productos t\u00edpicos de los terru\u00f1os de donde proceden las uvas.<\/p>\n<p>[\/et_pb_toggle][et_pb_text _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbHind||||||||\u00bb custom_margin=\u00bb||11px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Otra informaci\u00f3n<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbdisplay: flex;||justify-content: space-between;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbDuraci\u00f3n\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe06b;||divi||400&#8243; image_icon_width=\u00bb70px\u00bb image_icon_width_tablet=\u00bb50px\u00bb image_icon_width_phone=\u00bb40px\u00bb image_icon_width_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb14px\u00bb body_text_align=\u00bbcenter\u00bb body_font_size=\u00bb12px\u00bb body_line_height=\u00bb0.7em\u00bb module_alignment=\u00bbcenter\u00bb header_font_size_tablet=\u00bb12px\u00bb header_font_size_phone=\u00bb11px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb10px\u00bb body_font_size_phone=\u00bb10px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<ul>\n<li style=\"text-align: left;\">Tour<\/li>\n<\/ul>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbPunto de encuentro\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf3c5;||fa||900&#8243; image_icon_width=\u00bb70px\u00bb image_icon_width_tablet=\u00bb50px\u00bb image_icon_width_phone=\u00bb40px\u00bb image_icon_width_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb14px\u00bb body_text_align=\u00bbcenter\u00bb body_font_size=\u00bb12px\u00bb body_line_height=\u00bb0.7em\u00bb module_alignment=\u00bbcenter\u00bb header_font_size_tablet=\u00bb12px\u00bb header_font_size_phone=\u00bb11px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb10px\u00bb body_font_size_phone=\u00bb10px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<ul>\n<li style=\"text-align: left;\">Estaci\u00f3n de Catania<\/li>\n<li style=\"text-align: left;\">Hotel<\/li>\n<\/ul>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbINCLUYE\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf058;||fa||900&#8243; image_icon_width=\u00bb70px\u00bb image_icon_width_tablet=\u00bb50px\u00bb image_icon_width_phone=\u00bb40px\u00bb image_icon_width_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb14px\u00bb body_text_align=\u00bbleft\u00bb body_font_size=\u00bb12px\u00bb body_line_height=\u00bb0.7em\u00bb module_alignment=\u00bbcenter\u00bb header_font_size_tablet=\u00bb12px\u00bb header_font_size_phone=\u00bb11px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb10px\u00bb body_font_size_phone=\u00bb10px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<ul>\n<li>Conductor<\/li>\n<li>Vino, antipasto<\/li>\n<\/ul>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||22px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbdisplay: flex;||justify-content: space-between;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbNO INCLUYE\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe051;||divi||400&#8243; image_icon_width=\u00bb70px\u00bb icon_color_tablet=\u00bb\u00bb icon_color_phone=\u00bb\u00bb icon_color_last_edited=\u00bbon|desktop\u00bb image_icon_width_tablet=\u00bb50px\u00bb image_icon_width_phone=\u00bb40px\u00bb image_icon_width_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb14px\u00bb body_text_align=\u00bbcenter\u00bb body_font_size=\u00bb12px\u00bb body_line_height=\u00bb0.7em\u00bb module_alignment=\u00bbcenter\u00bb header_font_size_tablet=\u00bb12px\u00bb header_font_size_phone=\u00bb11px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb10px\u00bb body_font_size_phone=\u00bb10px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbITINERARIO\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf4d7;||fa||900&#8243; image_icon_width=\u00bb70px\u00bb icon_color_tablet=\u00bb\u00bb icon_color_phone=\u00bb\u00bb icon_color_last_edited=\u00bbon|phone\u00bb image_icon_width_tablet=\u00bb50px\u00bb image_icon_width_phone=\u00bb40px\u00bb image_icon_width_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb14px\u00bb body_text_align=\u00bbcenter\u00bb body_font_size=\u00bb12px\u00bb body_line_height=\u00bb0.7em\u00bb module_alignment=\u00bbcenter\u00bb header_font_size_tablet=\u00bb12px\u00bb header_font_size_phone=\u00bb11px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_text_color_tablet=\u00bb\u00bb body_text_color_phone=\u00bb\u00bb body_text_color_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb10px\u00bb body_font_size_phone=\u00bb10px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<ul>\n<li style=\"text-align: left;\">Horario acordado<\/li>\n<\/ul>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#ccb6a4&#8243; divider_weight=\u00bb2px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb width=\u00bb50%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb3px||5px||false|false\u00bb custom_margin_tablet=\u00bb3px||5px||false|false\u00bb custom_margin_phone=\u00bb3px||5px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb27px|15px|7px|24px|false|false\u00bb animation_style=\u00bbslide\u00bb border_radii=\u00bbon|7px|7px|7px|7px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbHind||||||||\u00bb custom_margin=\u00bb||11px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Pol\u00edticas de servicio<\/h3>\n<p>[\/et_pb_text][et_pb_toggle title=\u00bb\u00bfCu\u00e1les son las pol\u00edticas y condiciones?\u00bb icon_color=\u00bb#0C71C3&#8243; open_icon_color=\u00bb#E09900&#8243; open_use_icon_font_size=\u00bbon\u00bb open_icon_font_size=\u00bb21px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb title_font_size=\u00bb14px\u00bb border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<ul>\n<li lang=\"en-US\" class=\"western\"> Es posible elegir un Tour, una Experiencia o un Traslado o varias opciones al mismo tiempo.<\/li>\n<li lang=\"en-US\" class=\"western\">Nos pondremos en contacto con usted para presentarle el itinerario de lo que haya seleccionado.<\/li>\n<li lang=\"en-US\" class=\"western\"> Le presentaremos el precio total a pagar, que deber\u00e1 abonar al 30% de la reserva y el resto del importe podr\u00e1 abonarse en el momento del check-in.<\/li>\n<li lang=\"en-US\" class=\"western\">Le enviaremos los detalles del pago, que puede realizarse por transferencia bancaria.<\/li>\n<li lang=\"en-US\" class=\"western\"> El importe restante a pagar se abonar\u00e1 una vez se realice el encuentro con su gu\u00eda o responsable del tour,<\/li>\n<li lang=\"en-US\" class=\"western\">TRANSPORTE &#8211; El pago de los transportes pueden efectuarse \u00edntegramente en efectivo en el momento del encuentro.<\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00bb\u00bfCu\u00e1les son las condiciones de cancelaci\u00f3n?\u00bb icon_color=\u00bb#0C71C3&#8243; open_icon_color=\u00bb#E09900&#8243; open_use_icon_font_size=\u00bbon\u00bb open_icon_font_size=\u00bb21px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb title_font_size=\u00bb14px\u00bb border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<ul>\n<li>Las solicitudes de cancelaci\u00f3n o modificaci\u00f3n deben enviarse por correo electr\u00f3nico a info@tourtosicily.com para que tengamos constancia por escrito de la fecha y hora de la solicitud.<\/li>\n<li> Cancelaci\u00f3n m\u00e1s de 72 horas antes de la actividad: sin gastos. Se reembolsar\u00e1 al cliente el importe total abonado.<\/li>\n<li> Cancelaci\u00f3n menos de 72 horas antes de la actividad o no presentaci\u00f3n: 100% del importe total abonado. No se reembolsar\u00e1 el importe abonado.<\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbHind|500|||||||\u00bb header_font=\u00bbHind||||||||\u00bb custom_margin=\u00bb||11px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Otra informaci\u00f3n<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb-11px||||false|false\u00bb custom_margin_tablet=\u00bb-11px||||false|false\u00bb custom_margin_phone=\u00bb-11px||||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#ccb6a4&#8243; divider_weight=\u00bb5px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb width=\u00bb50%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb-25px||||false|false\u00bb custom_margin_tablet=\u00bb-25px||||false|false\u00bb custom_margin_phone=\u00bb-30px||||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/tourtosicily.com\/es\/preguntas-mas-frecuentes\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbPreguntas frecuentes\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb18px\u00bb button_border_width=\u00bb1px\u00bb button_font=\u00bbPoppins||||||||\u00bb button_icon=\u00bb&#xe064;||divi||400&#8243; button_on_hover=\u00bboff\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset1&#8243; box_shadow_blur=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][et_pb_divider color=\u00bb#ccb6a4&#8243; divider_weight=\u00bb5px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb width=\u00bb100%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb-25px||||false|false\u00bb custom_margin_tablet=\u00bb-25px||||false|false\u00bb custom_margin_phone=\u00bb-30px||||false|false\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb background_color=\u00bb#FFFFFF\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||-1px||false|false\u00bb custom_padding=\u00bb14px||14px||true|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">\u00bfTiene alguna pregunta?<\/h2>\n<p style=\"text-align: center;\">Contacto<\/p>\n<p>[\/et_pb_text][et_pb_icon font_icon=\u00bb&#xf879;||fa||900&#8243; icon_width=\u00bb35px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_text _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-17px||0px||false|false\u00bb custom_padding=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4 style=\"text-align: center;\">+039- 3515727069<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row padding_top_bottom_link_1=\u00bbfalse\u00bb _builder_version=\u00bb4.19.5&#8243; background_color=\u00bb#ffffff\u00bb custom_margin=\u00bb-25px||||false|false\u00bb custom_padding=\u00bb18px|10%|31px|10%|false|true\u00bb border_radii=\u00bb|||10px|10px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb100px\u00bb box_shadow_blur=\u00bb200px\u00bb box_shadow_spread=\u00bb-16px\u00bb box_shadow_color=\u00bbrgba(85,103,127,0.3)\u00bb custom_width_px__hover=\u00bb1080px\u00bb custom_width_px__hover_enabled=\u00bb1080px\u00bb custom_width_percent__hover=\u00bb80%\u00bb custom_width_percent__hover_enabled=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb use_custom_gutter__hover=\u00bboff\u00bb use_custom_gutter__hover_enabled=\u00bboff\u00bb gutter_width__hover=\u00bb3&#8243; gutter_width__hover_enabled=\u00bb3&#8243; parallax_1__hover=\u00bboff\u00bb parallax_1__hover_enabled=\u00bboff\u00bb parallax_2__hover=\u00bboff\u00bb parallax_2__hover_enabled=\u00bboff\u00bb parallax_3__hover=\u00bboff\u00bb parallax_3__hover_enabled=\u00bboff\u00bb parallax_4__hover=\u00bboff\u00bb parallax_4__hover_enabled=\u00bboff\u00bb parallax_5__hover=\u00bboff\u00bb parallax_5__hover_enabled=\u00bboff\u00bb parallax_6__hover=\u00bboff\u00bb parallax_6__hover_enabled=\u00bboff\u00bb parallax_method_1__hover=\u00bbon\u00bb parallax_method_1__hover_enabled=\u00bbon\u00bb parallax_method_2__hover=\u00bbon\u00bb parallax_method_2__hover_enabled=\u00bbon\u00bb parallax_method_3__hover=\u00bbon\u00bb parallax_method_3__hover_enabled=\u00bbon\u00bb parallax_method_4__hover=\u00bbon\u00bb parallax_method_4__hover_enabled=\u00bbon\u00bb parallax_method_5__hover=\u00bbon\u00bb parallax_method_5__hover_enabled=\u00bbon\u00bb parallax_method_6__hover=\u00bbon\u00bb parallax_method_6__hover_enabled=\u00bbon\u00bb box_shadow_style__hover=\u00bbnone\u00bb box_shadow_style__hover_enabled=\u00bbnone\u00bb box_shadow_color__hover=\u00bbrgba(0,0,0,0.3)\u00bb box_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.3)\u00bb use_custom_width__hover=\u00bboff\u00bb use_custom_width__hover_enabled=\u00bboff\u00bb use_background_color_gradient__hover=\u00bboff\u00bb use_background_color_gradient__hover_enabled=\u00bboff\u00bb background_color_gradient_start__hover=\u00bb#2b87da\u00bb background_color_gradient_start__hover_enabled=\u00bb#2b87da\u00bb background_color_gradient_end__hover=\u00bb#29c4a9&#8243; background_color_gradient_end__hover_enabled=\u00bb#29c4a9&#8243; background_color_gradient_type__hover=\u00bblinear\u00bb background_color_gradient_type__hover_enabled=\u00bblinear\u00bb background_color_gradient_direction__hover=\u00bb180deg\u00bb background_color_gradient_direction__hover_enabled=\u00bb180deg\u00bb background_color_gradient_direction_radial__hover=\u00bbcenter\u00bb background_color_gradient_direction_radial__hover_enabled=\u00bbcenter\u00bb background_color_gradient_start_position__hover=\u00bb0%\u00bb background_color_gradient_start_position__hover_enabled=\u00bb0%\u00bb background_color_gradient_end_position__hover=\u00bb100%\u00bb background_color_gradient_end_position__hover_enabled=\u00bb100%\u00bb background_color_gradient_overlays_image__hover=\u00bboff\u00bb background_color_gradient_overlays_image__hover_enabled=\u00bboff\u00bb parallax__hover=\u00bboff\u00bb parallax__hover_enabled=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb parallax_method__hover_enabled=\u00bbon\u00bb background_size__hover=\u00bbcover\u00bb background_size__hover_enabled=\u00bbcover\u00bb background_position__hover=\u00bbcenter\u00bb background_position__hover_enabled=\u00bbcenter\u00bb background_repeat__hover=\u00bbno-repeat\u00bb background_repeat__hover_enabled=\u00bbno-repeat\u00bb background_blend__hover=\u00bbnormal\u00bb background_blend__hover_enabled=\u00bbnormal\u00bb allow_player_pause__hover=\u00bboff\u00bb allow_player_pause__hover_enabled=\u00bboff\u00bb background_video_pause_outside_viewport__hover=\u00bbon\u00bb background_video_pause_outside_viewport__hover_enabled=\u00bbon\u00bb make_fullwidth__hover=\u00bboff\u00bb make_fullwidth__hover_enabled=\u00bboff\u00bb width_unit__hover=\u00bbon\u00bb width_unit__hover_enabled=\u00bbon\u00bb make_equal__hover=\u00bboff\u00bb make_equal__hover_enabled=\u00bboff\u00bb border_radii__hover=\u00bbon||||\u00bb border_radii__hover_enabled=\u00bbon||||\u00bb filter_hue_rotate__hover=\u00bb0deg\u00bb filter_hue_rotate__hover_enabled=\u00bb0deg\u00bb filter_saturate__hover=\u00bb100%\u00bb filter_saturate__hover_enabled=\u00bb100%\u00bb filter_brightness__hover=\u00bb100%\u00bb filter_brightness__hover_enabled=\u00bb100%\u00bb filter_contrast__hover=\u00bb100%\u00bb filter_contrast__hover_enabled=\u00bb100%\u00bb filter_invert__hover=\u00bb0%\u00bb filter_invert__hover_enabled=\u00bb0%\u00bb filter_sepia__hover=\u00bb0%\u00bb filter_sepia__hover_enabled=\u00bb0%\u00bb filter_opacity__hover=\u00bb100%\u00bb filter_opacity__hover_enabled=\u00bb100%\u00bb filter_blur__hover=\u00bb0px\u00bb filter_blur__hover_enabled=\u00bb0px\u00bb mix_blend_mode__hover=\u00bbnormal\u00bb mix_blend_mode__hover_enabled=\u00bbnormal\u00bb animation_style__hover=\u00bbnone\u00bb animation_style__hover_enabled=\u00bbnone\u00bb animation_repeat__hover=\u00bbonce\u00bb animation_repeat__hover_enabled=\u00bbonce\u00bb animation_direction__hover=\u00bbcenter\u00bb animation_direction__hover_enabled=\u00bbcenter\u00bb animation_duration__hover=\u00bb1000ms\u00bb animation_duration__hover_enabled=\u00bb1000ms\u00bb animation_delay__hover=\u00bb0ms\u00bb animation_delay__hover_enabled=\u00bb0ms\u00bb animation_intensity_slide__hover=\u00bb50%\u00bb animation_intensity_slide__hover_enabled=\u00bb50%\u00bb animation_intensity_zoom__hover=\u00bb50%\u00bb animation_intensity_zoom__hover_enabled=\u00bb50%\u00bb animation_intensity_flip__hover=\u00bb50%\u00bb animation_intensity_flip__hover_enabled=\u00bb50%\u00bb animation_intensity_fold__hover=\u00bb50%\u00bb animation_intensity_fold__hover_enabled=\u00bb50%\u00bb animation_intensity_roll__hover=\u00bb50%\u00bb animation_intensity_roll__hover_enabled=\u00bb50%\u00bb animation_starting_opacity__hover=\u00bb0%\u00bb animation_starting_opacity__hover_enabled=\u00bb0%\u00bb animation_speed_curve__hover=\u00bbease-in-out\u00bb animation_speed_curve__hover_enabled=\u00bbease-in-out\u00bb hover_transition_duration__hover=\u00bb300ms\u00bb hover_transition_duration__hover_enabled=\u00bb300ms\u00bb hover_transition_delay__hover=\u00bb0ms\u00bb hover_transition_delay__hover_enabled=\u00bb0ms\u00bb hover_transition_speed_curve__hover=\u00bbease\u00bb hover_transition_speed_curve__hover_enabled=\u00bbease\u00bb background_color_gradient_stops__hover=\u00bb#2b87da 0%|#29c4a9 100%\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb26px\u00bb header_font=\u00bbHind||||||||\u00bb header_2_font=\u00bbHind|500|||||||\u00bb header_2_font_size=\u00bb35px\u00bb header_2_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||12px|||\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb24px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_text][et_pb_divider color=\u00bb#ccb6a4&#8243; divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.19.5&#8243; max_width=\u00bb80px\u00bb module_alignment=\u00bbcenter\u00bb height=\u00bb3px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<br \/>\n[\/et_pb_divider][et_pb_contact_form captcha=\u00bboff\u00bb email=\u00bbinfo@tourtosicily.com\u00bb success_message=\u00bbGracias por ponerse en contacto con nosotros, responderemos a su pregunta lo antes posible.\u00bb submit_button_text=\u00bbEnviar\u00bb _builder_version=\u00bb4.20.1&#8243; form_field_background_color=\u00bbrgba(211,211,211,0.67)\u00bb form_field_font=\u00bbOpen Sans||||||||\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#076d95&#8243; button_border_width=\u00bb6px\u00bb button_border_color=\u00bbrgba(0,0,0,0)\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb3px\u00bb button_font=\u00bbPoppins|500||on|||||\u00bb button_icon=\u00bb&#x24;||divi||400&#8243; button_custom_padding=\u00bb6px||6px||true|false\u00bb custom_margin=\u00bb30px|||||\u00bb border_radii=\u00bbon|13px|13px|13px|13px\u00bb form_background_color=\u00bbrgba(85,103,127,0.06)\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_contact_field field_id=\u00bbNome\u00bb field_title=\u00bbNombre\u00bb _builder_version=\u00bb4.19.5&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbEmail\u00bb field_title=\u00bbCorreo electr\u00f3nico \u00bb field_type=\u00bbemail\u00bb _builder_version=\u00bb4.19.5&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessaggio\u00bb field_title=\u00bbMensaje\u00bb field_type=\u00bbtext\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.19.5&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbPrivacidad\u00bb field_title=\u00bb \u00bb field_type=\u00bbcheckbox\u00bb checkbox_options=\u00bb%91{%22value%22:%22Leggere e accettare l&#8217;informativa sulla privacy%22,%22checked%22:0,%22dragID%22:-1,%22link_url%22:%22https:\/\/tourtosicily.com\/politica-de-privacidad\/%22}%93&#8243; fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.20.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb-7px||||false|false\u00bb custom_margin_tablet=\u00bb-7px||||false|false\u00bb custom_margin_phone=\u00bb-6px||||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#ccb6a4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_tabs include_tabs=\u00bb||reviews\u00bb _builder_version=\u00bb4.20.1&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bbon|7px|7px|7px|7px\u00bb border_width_all=\u00bb0px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_tabs][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<h3 class=\"western\" lang=\"en-US\" style=\"text-align: center;\"><strong>Itinerario eno-gastron\u00f3mico para descubrir los sabores del volc\u00e1n<\/strong><\/h3>\n<p class=\"western\">Sicilia es la regi\u00f3n con la tradici\u00f3n vin\u00edcola m\u00e1s antigua Tan antigua que roza la leyenda: la imagen del tembloroso Odiseo sirviendo copas de vino al gigante Polifemo ha marcado profundamente el imaginario colectivo del mundo occidental.<\/p>\n<p class=\"western\">Y el gigante con un ojo, lanzando pedruscos, no es m\u00e1s que una sugestiva representaci\u00f3n simb\u00f3lica de un cr\u00e1ter, (o del propio volc\u00e1n) tal y como apareci\u00f3 ante los ojos fascinados e intimidados de los primeros colonos griegos que se acercaron a \u00e9l en el siglo VIII a.C.<\/p>\n<p class=\"western\">De ah\u00ed que la combinaci\u00f3n de Etna y vino tenga una tradici\u00f3n multi milenaria, profundamente arraigada aqu\u00ed, como demuestran las monedas acu\u00f1adas en el siglo V a.C. y la existencia de numerosas variedades de vid ya cultivadas en aquella \u00e9poca y de antiguas pr\u00e1cticas de vendimia y vinificaci\u00f3n.<\/p>\n<p class=\"western\">No es casualidad que los propios griegos llamaran a esta tierra \u00abEnotria\u00bb. Y el vino ha sido durante mucho tiempo un punto de referencia constante en la agricultura y la econom\u00eda de estas comarcas.<\/p>\n<p class=\"western\">En las \u00faltimas d\u00e9cadas, se han realizado numerosas innovaciones para mejorar el producto y se ha experimentado con nuevas variedades, con resultados realmente sorprendentes y merecidos premios.<\/p>\n<p class=\"western\">Los atractivos del Etna, por tanto, no se limitan a la geolog\u00eda y vulcanolog\u00eda del mayor volc\u00e1n activo de Europa, sino que tambi\u00e9n abarcan sorprendentes esferas sensoriales, para deleite del turista gourmet.<\/p>\n<p class=\"western\">El rico y variado paisaje no se limita a sombr\u00edos atisbos de entornos de lava lunar, sino que se alterna con una extraordinaria riqueza de vegetaci\u00f3n, a menudo caracterizada por cultivos t\u00edpicos. Las ferias y fiestas locales ofrecen peri\u00f3dicamente los sabores m\u00e1s aut\u00e9nticos del volc\u00e1n: junto al vino, el sublime n\u00e9ctar de estas tierras, casta\u00f1as y setas de los bosques, pistachos de Bronte, chumberas de Belpasso y Biancavilla, miel de Zafferana, avellanas del Valle de Alc\u00e1ntara.<\/p>\n<p class=\"western\">El itinerario que proponemos pretende combinar el disfrute del paisaje etneano con la degustaci\u00f3n de productos t\u00edpicos de la zona.<\/p>\n<p class=\"western\">La excursi\u00f3n\u00a0 tocar\u00e1 los lugares m\u00e1s llamativos del volc\u00e1n.<\/p>\n<p class=\"western\">Tras admirar los bosques, los cr\u00e1teres y las coladas de lava antiguas y recientes, det\u00e9ngase en una bodega de la vertiente oriental para visitar el vi\u00f1edo, las bodegas y degustar una buena copa de Etna Rosso, acompa\u00f1ado de los platos t\u00edpicos sicilianos m\u00e1s adecuados a la temporada: caponata, parmigiana, tortillas rellenas, timbal de berenjenas, aceitunas, embutidos y quesos.<\/p>\n","protected":false},"featured_media":3885,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[]},"product_brand":[],"product_cat":[333],"product_tag":[312,314,347,321,346,345,334,335],"class_list":["post-4404","product","type-product","status-publish","has-post-thumbnail","product_cat-experiencia","product_tag-catania-es","product_tag-comida","product_tag-el-etna-y-el-vino","product_tag-experiencias","product_tag-gastronomia-y-vinos","product_tag-la-comida-siciliana","product_tag-tours-es","product_tag-vino-es","first","instock","featured","taxable","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Etna y el vino - Mywaytosicily.com<\/title>\n<meta name=\"description\" content=\"Sicilia es la regi\u00f3n con la tradici\u00f3n vin\u00edcola m\u00e1s antigua Tan antigua que roza la leyenda: la imagen del tembloroso Odiseo sirviendo copas de vino al gigante Polifemo ha marcado profundamente el imaginario colectivo del mundo occidental.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Etna y el vino - Mywaytosicily.com\" \/>\n<meta property=\"og:description\" content=\"Sicilia es la regi\u00f3n con la tradici\u00f3n vin\u00edcola m\u00e1s antigua Tan antigua que roza la leyenda: la imagen del tembloroso Odiseo sirviendo copas de vino al gigante Polifemo ha marcado profundamente el imaginario colectivo del mundo occidental.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/\" \/>\n<meta property=\"og:site_name\" content=\"Mywaytosicily.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100090741942876\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T09:39:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/mywaytosicily.com\/wp-content\/uploads\/2023\/02\/recolectavino-1.jpg?fit=580%2C582&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/producto\\\/el-etna-y-el-vino\\\/\",\"url\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/producto\\\/el-etna-y-el-vino\\\/\",\"name\":\"El Etna y el vino - Mywaytosicily.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/producto\\\/el-etna-y-el-vino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/producto\\\/el-etna-y-el-vino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/mywaytosicily.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/recolectavino-1.jpg?fit=580%2C582&ssl=1\",\"datePublished\":\"2023-03-09T19:37:11+00:00\",\"dateModified\":\"2023-03-21T09:39:01+00:00\",\"description\":\"Sicilia es la regi\u00f3n con la tradici\u00f3n vin\u00edcola m\u00e1s antigua Tan antigua que roza la leyenda: la imagen del tembloroso Odiseo sirviendo copas de vino al gigante Polifemo ha marcado profundamente el imaginario colectivo del mundo occidental.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/producto\\\/el-etna-y-el-vino\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/producto\\\/el-etna-y-el-vino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/producto\\\/el-etna-y-el-vino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mywaytosicily.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/recolectavino-1.jpg?fit=580%2C582&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mywaytosicily.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/recolectavino-1.jpg?fit=580%2C582&ssl=1\",\"width\":580,\"height\":582},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/producto\\\/el-etna-y-el-vino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/mywaytosicily.com\\\/?page_id=2500\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Etna y el vino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/\",\"name\":\"My Way To Sicily\",\"description\":\"My Way Transfer and tours in Sicily\",\"publisher\":{\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/#organization\"},\"alternateName\":\"Mywaytosicily.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/#organization\",\"name\":\"My Way To Sicily\",\"url\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"My Way To Sicily\"},\"image\":{\"@id\":\"https:\\\/\\\/mywaytosicily.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100090741942876\",\"https:\\\/\\\/www.instagram.com\\\/mywaycatania\\\/?igshid=YmMyMTA2M2Y\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Etna y el vino - Mywaytosicily.com","description":"Sicilia es la regi\u00f3n con la tradici\u00f3n vin\u00edcola m\u00e1s antigua Tan antigua que roza la leyenda: la imagen del tembloroso Odiseo sirviendo copas de vino al gigante Polifemo ha marcado profundamente el imaginario colectivo del mundo occidental.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/","og_locale":"es_ES","og_type":"article","og_title":"El Etna y el vino - Mywaytosicily.com","og_description":"Sicilia es la regi\u00f3n con la tradici\u00f3n vin\u00edcola m\u00e1s antigua Tan antigua que roza la leyenda: la imagen del tembloroso Odiseo sirviendo copas de vino al gigante Polifemo ha marcado profundamente el imaginario colectivo del mundo occidental.","og_url":"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/","og_site_name":"Mywaytosicily.com","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100090741942876","article_modified_time":"2023-03-21T09:39:01+00:00","og_image":[{"width":580,"height":582,"url":"https:\/\/i0.wp.com\/mywaytosicily.com\/wp-content\/uploads\/2023\/02\/recolectavino-1.jpg?fit=580%2C582&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/","url":"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/","name":"El Etna y el vino - Mywaytosicily.com","isPartOf":{"@id":"https:\/\/mywaytosicily.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/#primaryimage"},"image":{"@id":"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/mywaytosicily.com\/wp-content\/uploads\/2023\/02\/recolectavino-1.jpg?fit=580%2C582&ssl=1","datePublished":"2023-03-09T19:37:11+00:00","dateModified":"2023-03-21T09:39:01+00:00","description":"Sicilia es la regi\u00f3n con la tradici\u00f3n vin\u00edcola m\u00e1s antigua Tan antigua que roza la leyenda: la imagen del tembloroso Odiseo sirviendo copas de vino al gigante Polifemo ha marcado profundamente el imaginario colectivo del mundo occidental.","breadcrumb":{"@id":"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/#primaryimage","url":"https:\/\/i0.wp.com\/mywaytosicily.com\/wp-content\/uploads\/2023\/02\/recolectavino-1.jpg?fit=580%2C582&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mywaytosicily.com\/wp-content\/uploads\/2023\/02\/recolectavino-1.jpg?fit=580%2C582&ssl=1","width":580,"height":582},{"@type":"BreadcrumbList","@id":"https:\/\/mywaytosicily.com\/es\/producto\/el-etna-y-el-vino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mywaytosicily.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/mywaytosicily.com\/?page_id=2500"},{"@type":"ListItem","position":3,"name":"El Etna y el vino"}]},{"@type":"WebSite","@id":"https:\/\/mywaytosicily.com\/es\/#website","url":"https:\/\/mywaytosicily.com\/es\/","name":"My Way To Sicily","description":"My Way Transfer and tours in Sicily","publisher":{"@id":"https:\/\/mywaytosicily.com\/es\/#organization"},"alternateName":"Mywaytosicily.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mywaytosicily.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mywaytosicily.com\/es\/#organization","name":"My Way To Sicily","url":"https:\/\/mywaytosicily.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mywaytosicily.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"My Way To Sicily"},"image":{"@id":"https:\/\/mywaytosicily.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100090741942876","https:\/\/www.instagram.com\/mywaycatania\/?igshid=YmMyMTA2M2Y"]}]}},"jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"_links":{"self":[{"href":"https:\/\/mywaytosicily.com\/es\/wp-json\/wp\/v2\/product\/4404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mywaytosicily.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mywaytosicily.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mywaytosicily.com\/es\/wp-json\/wp\/v2\/comments?post=4404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mywaytosicily.com\/es\/wp-json\/wp\/v2\/media\/3885"}],"wp:attachment":[{"href":"https:\/\/mywaytosicily.com\/es\/wp-json\/wp\/v2\/media?parent=4404"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mywaytosicily.com\/es\/wp-json\/wp\/v2\/product_brand?post=4404"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mywaytosicily.com\/es\/wp-json\/wp\/v2\/product_cat?post=4404"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mywaytosicily.com\/es\/wp-json\/wp\/v2\/product_tag?post=4404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}